{"id":691,"count":1,"description":"","link":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/","name":"country property","slug":"country-property","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>country property archivos - Blog about Menorca - Ses Moreres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"country property archivos - Blog about Menorca - Ses Moreres\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog about Menorca - Ses Moreres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/category\\\/country-property\\\/\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/category\\\/country-property\\\/\",\"name\":\"country property archivos - Blog about Menorca - Ses Moreres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/category\\\/country-property\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/category\\\/country-property\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"country property\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/\",\"name\":\"Blog about Menorca - Ses Moreres\",\"description\":\"Estate Agents in Menorca - Leader selling deluxe properties Rustic farms, country houses, chalets, land\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sesmoreres.com\\\/en\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"country property archivos - Blog about Menorca - Ses Moreres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/","og_locale":"en_US","og_type":"article","og_title":"country property archivos - Blog about Menorca - Ses Moreres","og_url":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/","og_site_name":"Blog about Menorca - Ses Moreres","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/","url":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/","name":"country property archivos - Blog about Menorca - Ses Moreres","isPartOf":{"@id":"https:\/\/www.sesmoreres.com\/en\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sesmoreres.com\/en\/blog\/category\/country-property\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sesmoreres.com\/en\/blog\/"},{"@type":"ListItem","position":2,"name":"country property"}]},{"@type":"WebSite","@id":"https:\/\/www.sesmoreres.com\/en\/blog\/#website","url":"https:\/\/www.sesmoreres.com\/en\/blog\/","name":"Blog about Menorca - Ses Moreres","description":"Estate Agents in Menorca - Leader selling deluxe properties Rustic farms, country houses, chalets, land","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sesmoreres.com\/en\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.sesmoreres.com\/en\/blog\/wp-json\/wp\/v2\/categories\/691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sesmoreres.com\/en\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sesmoreres.com\/en\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.sesmoreres.com\/en\/blog\/wp-json\/wp\/v2\/posts?categories=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}