{"id":561,"date":"2009-04-24T10:19:00","date_gmt":"2009-04-24T08:19:00","guid":{"rendered":"https:\/\/www.sesmoreres.com\/blog\/2009\/04\/24\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/"},"modified":"2020-04-01T17:48:38","modified_gmt":"2020-04-01T15:48:38","slug":"apartamento-en-la-playa-menorca-por-solo-98-000-euros","status":"publish","type":"post","link":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/","title":{"rendered":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!!"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Debido a la gran expectaci\u00f3n producida por la oferta de la semana pasada, nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran oportunidad en <strong><a href=\"https:\/\/www.sesmoreres.com\/resultado-busqueda\/?a=&amp;pag=0&amp;o=&amp;s=&amp;pp=&amp;search=cala%20galdana&amp;op=\">Cala Galdana<\/a><\/strong>. Nos referimos a un apartamento de 2 habitaciones con estupendas vistas al campo y a escasos 500 metros de la playa. Debajo pod\u00e9is verlo en nuestro v\u00eddeo<\/p>\n<p>.<\/p>\n<p><iframe data-src=\"https:\/\/www.youtube.com\/embed\/HIxy2Tb4bk0\" width=\"480\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n hemos querido mostraros un poco m\u00e1s de los encantos de la playa de aguas cristalinas de Cala Galdana en este nuevo v\u00eddeo<\/p>\n<p><iframe data-src=\"https:\/\/www.youtube.com\/embed\/R1LMWNkRwmI\" width=\"480\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>M\u00e1s informaci\u00f3n <a href=\"mailto:inversiones@sesmoreres.com?subject=Info%20Casa%203%20platas%20en%20Mahon%20Menorca&amp;body=Quiero%20mas%20informacion\">inversiones@sesmoreres.com<\/a> o llama al <a href=\"tel:+34971351530\">Tel +34 971 35 15 30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Debido a la gran expectaci\u00f3n producida por la oferta de la semana pasada, nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran oportunidad en Cala Galdana. Nos referimos a un apartamento de 2 habitaciones con estupendas &hellip; <a href=\"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/\">Continuar<\/a><\/p>\n","protected":false},"author":2,"featured_media":1312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[576],"tags":[703,629,709,628,610,615,687,708],"class_list":["post-561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cala-galdana-menorca-baleares-apartamento-chollo-ganda-menorca-embargo-inmobiliaria-playa-oportunidad-barato","tag-aparamento-en-venta","tag-cala-galdana","tag-comprar","tag-ferreries","tag-menorca","tag-playa","tag-real-estate","tag-vacaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apartamento en la playa (Menorca) por solo 98.000 Euros!!! - Blog sobre Menorca - Ses Moreres<\/title>\n<meta name=\"description\" content=\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! Nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! - Blog sobre Menorca - Ses Moreres\" \/>\n<meta property=\"og:description\" content=\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! Nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog sobre Menorca - Ses Moreres\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sesmoreres\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-24T08:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-01T15:48:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2009\/04\/03-apartment-for-sale-cala-galadana-menorca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"598\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/\"},\"author\":{\"name\":\"Jose\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#\\\/schema\\\/person\\\/7c7e14840c5091c536f2386f87710e37\"},\"headline\":\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!!\",\"datePublished\":\"2009-04-24T08:19:00+00:00\",\"dateModified\":\"2020-04-01T15:48:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/\"},\"wordCount\":106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/03-apartment-for-sale-cala-galadana-menorca.jpg\",\"keywords\":[\"aparamento en venta\",\"Cala Galdana\",\"comprar\",\"Ferreries\",\"menorca\",\"playa\",\"real estate\",\"vacaciones\"],\"articleSection\":[\"Cala Galdana Menorca Baleares apartamento chollo ganda menorca embargo inmobiliaria playa oportunidad barato\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/\",\"name\":\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! - Blog sobre Menorca - Ses Moreres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/03-apartment-for-sale-cala-galadana-menorca.jpg\",\"datePublished\":\"2009-04-24T08:19:00+00:00\",\"dateModified\":\"2020-04-01T15:48:38+00:00\",\"description\":\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! Nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/03-apartment-for-sale-cala-galadana-menorca.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/03-apartment-for-sale-cala-galadana-menorca.jpg\",\"width\":598,\"height\":453,\"caption\":\"Apartamento en Cala Galdana, Menorca por solo 83.000 Euros\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apartamento en la playa (Menorca) por solo 98.000 Euros!!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/\",\"name\":\"Blog sobre Menorca - Ses Moreres\",\"description\":\"Agencia inmobiliaria de Menorca lider en la venta de propiedades de lujo. Fincas r\u00fasticas, casas de campo, chalets, terrenos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#organization\",\"name\":\"Ses Moreres\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/ses-moreres-inmobiliaria-menorca.gif\",\"contentUrl\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/ses-moreres-inmobiliaria-menorca.gif\",\"width\":170,\"height\":95,\"caption\":\"Ses Moreres\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sesmoreres\\\/\",\"https:\\\/\\\/www.instagram.com\\\/inmobiliariasesmoreres\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/sesmoreres\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/#\\\/schema\\\/person\\\/7c7e14840c5091c536f2386f87710e37\",\"name\":\"Jose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4fc98d81ad2dabadc7b38d8d9cc7d784080dca9704b983ca16b1fd2926445dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4fc98d81ad2dabadc7b38d8d9cc7d784080dca9704b983ca16b1fd2926445dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4fc98d81ad2dabadc7b38d8d9cc7d784080dca9704b983ca16b1fd2926445dc?s=96&d=mm&r=g\",\"caption\":\"Jose\"},\"url\":\"https:\\\/\\\/www.sesmoreres.com\\\/blog\\\/author\\\/jose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! - Blog sobre Menorca - Ses Moreres","description":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! Nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/","og_locale":"es_ES","og_type":"article","og_title":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! - Blog sobre Menorca - Ses Moreres","og_description":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! Nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran...","og_url":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/","og_site_name":"Blog sobre Menorca - Ses Moreres","article_publisher":"https:\/\/www.facebook.com\/sesmoreres\/","article_published_time":"2009-04-24T08:19:00+00:00","article_modified_time":"2020-04-01T15:48:38+00:00","og_image":[{"width":598,"height":453,"url":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2009\/04\/03-apartment-for-sale-cala-galadana-menorca.jpg","type":"image\/jpeg"}],"author":"Jose","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jose"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#article","isPartOf":{"@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/"},"author":{"name":"Jose","@id":"https:\/\/www.sesmoreres.com\/blog\/#\/schema\/person\/7c7e14840c5091c536f2386f87710e37"},"headline":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!!","datePublished":"2009-04-24T08:19:00+00:00","dateModified":"2020-04-01T15:48:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/"},"wordCount":106,"commentCount":0,"publisher":{"@id":"https:\/\/www.sesmoreres.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2009\/04\/03-apartment-for-sale-cala-galadana-menorca.jpg","keywords":["aparamento en venta","Cala Galdana","comprar","Ferreries","menorca","playa","real estate","vacaciones"],"articleSection":["Cala Galdana Menorca Baleares apartamento chollo ganda menorca embargo inmobiliaria playa oportunidad barato"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/","url":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/","name":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! - Blog sobre Menorca - Ses Moreres","isPartOf":{"@id":"https:\/\/www.sesmoreres.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#primaryimage"},"image":{"@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2009\/04\/03-apartment-for-sale-cala-galadana-menorca.jpg","datePublished":"2009-04-24T08:19:00+00:00","dateModified":"2020-04-01T15:48:38+00:00","description":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!! Nos hemos esforzado al m\u00e1ximo para poderos ofrecer de nuevo una gran...","breadcrumb":{"@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#primaryimage","url":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2009\/04\/03-apartment-for-sale-cala-galadana-menorca.jpg","contentUrl":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2009\/04\/03-apartment-for-sale-cala-galadana-menorca.jpg","width":598,"height":453,"caption":"Apartamento en Cala Galdana, Menorca por solo 83.000 Euros"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sesmoreres.com\/blog\/apartamento-en-la-playa-menorca-por-solo-98-000-euros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sesmoreres.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Apartamento en la playa (Menorca) por solo 98.000 Euros!!!"}]},{"@type":"WebSite","@id":"https:\/\/www.sesmoreres.com\/blog\/#website","url":"https:\/\/www.sesmoreres.com\/blog\/","name":"Blog sobre Menorca - Ses Moreres","description":"Agencia inmobiliaria de Menorca lider en la venta de propiedades de lujo. Fincas r\u00fasticas, casas de campo, chalets, terrenos.","publisher":{"@id":"https:\/\/www.sesmoreres.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sesmoreres.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sesmoreres.com\/blog\/#organization","name":"Ses Moreres","url":"https:\/\/www.sesmoreres.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sesmoreres.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2019\/07\/ses-moreres-inmobiliaria-menorca.gif","contentUrl":"https:\/\/www.sesmoreres.com\/blog\/wp-content\/uploads\/2019\/07\/ses-moreres-inmobiliaria-menorca.gif","width":170,"height":95,"caption":"Ses Moreres"},"image":{"@id":"https:\/\/www.sesmoreres.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sesmoreres\/","https:\/\/www.instagram.com\/inmobiliariasesmoreres\/?hl=es","https:\/\/www.youtube.com\/user\/sesmoreres"]},{"@type":"Person","@id":"https:\/\/www.sesmoreres.com\/blog\/#\/schema\/person\/7c7e14840c5091c536f2386f87710e37","name":"Jose","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b4fc98d81ad2dabadc7b38d8d9cc7d784080dca9704b983ca16b1fd2926445dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4fc98d81ad2dabadc7b38d8d9cc7d784080dca9704b983ca16b1fd2926445dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4fc98d81ad2dabadc7b38d8d9cc7d784080dca9704b983ca16b1fd2926445dc?s=96&d=mm&r=g","caption":"Jose"},"url":"https:\/\/www.sesmoreres.com\/blog\/author\/jose\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/posts\/561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/comments?post=561"}],"version-history":[{"count":4,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/posts\/561\/revisions"}],"predecessor-version":[{"id":1403,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/posts\/561\/revisions\/1403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/media\/1312"}],"wp:attachment":[{"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/media?parent=561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/categories?post=561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sesmoreres.com\/blog\/wp-json\/wp\/v2\/tags?post=561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}